{"id":8552,"date":"2024-02-09T08:29:00","date_gmt":"2024-02-09T07:29:00","guid":{"rendered":"https:\/\/solidanca.con2webs.es\/ponemos-en-marcha-el-nuevo-taller-de-circular-upcycling-la-coleccion-de-innovacion-textil-de-solidanca\/"},"modified":"2024-02-09T08:29:00","modified_gmt":"2024-02-09T07:29:00","slug":"ponemos-en-marcha-el-nuevo-taller-de-circular-upcycling-la-coleccion-de-innovacion-textil-de-solidanca","status":"publish","type":"post","link":"https:\/\/solidanca.cat\/es\/ponemos-en-marcha-el-nuevo-taller-de-circular-upcycling-la-coleccion-de-innovacion-textil-de-solidanca\/","title":{"rendered":"Ponemos en marcha el nuevo taller de Circular Upcycling, la colecci\u00f3n de innovaci\u00f3n textil de Solidan\u00e7a"},"content":{"rendered":"\n<p>El proyecto Circular\u00a0Upcycling, es un proyecto piloto e innovador que genera y mantiene puestos de trabajo para personas en situaci\u00f3n de vulnerabilidad social en la entidad, a trav\u00e9s de un taller de costura y confecci\u00f3n de piezas de upcycling\u00a0a partir de aprovechamiento de textil en desuso.<\/p>\n\n\n\n<p>Se trata de un espacio de investigaci\u00f3n y producci\u00f3n donde creamos piezas \u00fanicas con valor social y ambiental a trav\u00e9s del aprovechamiento y reutilizaci\u00f3n del residuo textil post-consumo, para posteriormente ponerlos a la venta a trav\u00e9s de nuestra tienda en l\u00ednea ( www.circularsecondhand.org ) y en las tiendas f\u00edsicas de Solidan\u00e7a \/ Ropa Amiga.<\/p>\n\n\n\n<p>Por un lado, con este proyecto evitamos que la ropa se convierta en desecho y acabe en vertederos e incineradoras. Al dar un segundo uso a productos ya fabricados, disminuimos el gasto energ\u00e9tico y la explotaci\u00f3n de recursos naturales que deber\u00edan invertirse en el proceso de fabricaci\u00f3n de una nueva pieza.<\/p>\n\n\n\n<p>Por otra parte, para promover los itinerarios de inserci\u00f3n desde la entidad, se ha contratado a una nueva persona encargada de costura y patronaje, a la vez que se mantienen dos puestos de trabajo para personas en situaci\u00f3n de vulnerabilidad social.<\/p>\n\n\n\n<p>Ante las necesidades del taller, el proyecto cuenta con una formaci\u00f3n especializada dentro del horario laboral para las personas trabajadoras del taller de costura y confecci\u00f3n. En esta formaci\u00f3n se introducen las diferentes t\u00e9cnicas de realizaci\u00f3n de los patrones base y sus transformaciones.<\/p>\n\n\n\n<p>Las nuevas prendas contar\u00e1n tambi\u00e9n con etiquetas sostenibles que sensibilicen a las consumidoras sobre la filosof\u00eda del tejido y la confecci\u00f3n, destacando el consumo responsable, la econom\u00eda circular y la creaci\u00f3n de empleo como valores esenciales.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>La nueva propuesta de valor de tejido de fieltro, un impulso por el taller<\/strong><\/p>\n\n\n\n<p>Solidan\u00e7a, junto con\u00a0Eurecat\u00a0\u2013 Centro Tecnol\u00f3gico de Catalu\u00f1a, iniciaron un estudio para buscar soluciones vinculadas al ecodise\u00f1o de nuevos productos que permitan abrir una oportunidad para mejorar la circularidad y la valorizaci\u00f3n de los materiales que actualmente recoge y gestiona Solidan\u00e7a.<\/p>\n\n\n\n<p>Gracias a esta colaboraci\u00f3n se ha generado un nuevo material textil de fieltro (no tejido) proveniente de residuo pre y post-consumo de Solidanza, recuperando fibra de poli\u00e9ster termopl\u00e1stico.<\/p>\n\n\n\n<p>La experimentaci\u00f3n ha definido y conceptualizado una gama de productos textiles a trav\u00e9s de la metodolog\u00eda del ecodise\u00f1o. Se ha contado con expertos dise\u00f1adores de Eurecat y con personas emprendedoras del ecodise\u00f1o que nos han permitido conceptualizar nuevas soluciones.<\/p>\n\n\n\n<p>El resultado de este tejido permitir\u00e1 crear nuevos productos en el taller a partir del fieltro reciclado, adem\u00e1s de la colecci\u00f3n de upcycling, que tambi\u00e9n se pondr\u00e1n a la venta en las tiendas f\u00edsicas y online de Solidanza\/ Ropa Amiga.<\/p>\n\n\n\n<p>Este proyecto est\u00e1 promovido por el Programa de Econom\u00eda Social y el Departamento de Empresa y Trabajo de la Generalidad de Catalu\u00f1a, y financiado por el Ministerio de Trabajo y Econom\u00eda Social.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/solidanca.cat\/wp-content\/uploads\/2024\/02\/LOGOS-CIRCULAR-UPCYCLING-1024x264.png\" alt=\"\" class=\"wp-image-17560\" width=\"644\" height=\"165\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto Circular\u00a0Upcycling, es un proyecto piloto e innovador que genera y mantiene puestos de trabajo para personas en situaci\u00f3n de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":7043,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[763,758,761,766],"tags":[],"class_list":["post-8552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-social-es","category-formacion","category-medio-ambiente","category-medio-ambienteroba-amiga"],"taxonomy_info":{"category":[{"value":763,"label":"Area Social"},{"value":758,"label":"Formaci\u00f3n"},{"value":761,"label":"MEDIO AMBIENTE"},{"value":766,"label":"Medio ambiente&gt;Roba Amiga"}]},"featured_image_src_large":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-02-01T120521.590-3.jpg",400,200,false],"author_info":{"display_name":"Solidan\u00e7a","author_link":"https:\/\/solidanca.cat\/es\/author\/alberg\/"},"comment_info":0,"category_info":[{"term_id":763,"name":"Area Social","slug":"area-social-es","term_group":0,"term_taxonomy_id":763,"taxonomy":"category","description":"","parent":0,"count":208,"filter":"raw","cat_ID":763,"category_count":208,"category_description":"","cat_name":"Area Social","category_nicename":"area-social-es","category_parent":0},{"term_id":758,"name":"Formaci\u00f3n","slug":"formacion","term_group":0,"term_taxonomy_id":758,"taxonomy":"category","description":"","parent":0,"count":107,"filter":"raw","cat_ID":758,"category_count":107,"category_description":"","cat_name":"Formaci\u00f3n","category_nicename":"formacion","category_parent":0},{"term_id":761,"name":"MEDIO AMBIENTE","slug":"medio-ambiente","term_group":0,"term_taxonomy_id":761,"taxonomy":"category","description":"","parent":0,"count":263,"filter":"raw","cat_ID":761,"category_count":263,"category_description":"","cat_name":"MEDIO AMBIENTE","category_nicename":"medio-ambiente","category_parent":0},{"term_id":766,"name":"Medio ambiente&gt;Roba Amiga","slug":"medio-ambienteroba-amiga","term_group":0,"term_taxonomy_id":766,"taxonomy":"category","description":"","parent":0,"count":61,"filter":"raw","cat_ID":766,"category_count":61,"category_description":"","cat_name":"Medio ambiente&gt;Roba Amiga","category_nicename":"medio-ambienteroba-amiga","category_parent":0}],"tag_info":false,"uagb_featured_image_src":{"full":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-02-01T120521.590-3.jpg",400,200,false],"thumbnail":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-02-01T120521.590-3-150x150.jpg",150,150,true],"medium":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-02-01T120521.590-3-300x150.jpg",300,150,true],"medium_large":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-02-01T120521.590-3.jpg",400,200,false],"large":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-02-01T120521.590-3.jpg",400,200,false],"1536x1536":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-02-01T120521.590-3.jpg",400,200,false],"2048x2048":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-02-01T120521.590-3.jpg",400,200,false]},"uagb_author_info":{"display_name":"Solidan\u00e7a","author_link":"https:\/\/solidanca.cat\/es\/author\/alberg\/"},"uagb_comment_info":0,"uagb_excerpt":"El proyecto Circular\u00a0Upcycling, es un proyecto piloto e innovador que genera y mantiene puestos de trabajo para personas en situaci\u00f3n de...","_links":{"self":[{"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/posts\/8552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/comments?post=8552"}],"version-history":[{"count":0,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/posts\/8552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/media\/7043"}],"wp:attachment":[{"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/media?parent=8552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/categories?post=8552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/tags?post=8552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}