{"id":8755,"date":"2024-10-29T12:43:05","date_gmt":"2024-10-29T11:43:05","guid":{"rendered":"https:\/\/solidanca.con2webs.es\/exito-en-el-mercado-de-abrigos-y-ropa-de-invierno-de-segunda-mano-en-solidanca\/"},"modified":"2024-10-29T12:43:08","modified_gmt":"2024-10-29T11:43:08","slug":"exito-en-el-mercado-de-abrigos-y-ropa-de-invierno-de-segunda-mano-en-solidanca","status":"publish","type":"post","link":"https:\/\/solidanca.cat\/es\/exito-en-el-mercado-de-abrigos-y-ropa-de-invierno-de-segunda-mano-en-solidanca\/","title":{"rendered":"\u00c9xito en el Mercado de abrigos y ropa de invierno de segunda mano en Solidan\u00e7a!"},"content":{"rendered":"<p>El s\u00e1bado 26 de octubre celebramos el primer Mercado de Abrigos y Ropa de invierno de segunda mano en la Planta de Preparaci\u00f3n Textil de Solidanza. El mercado ofrec\u00eda ropa de invierno a<a href=\"https:\/\/solidanca.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-29-a-las-13.28.03_d570d768.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-64550 alignright\" src=\"https:\/\/solidanca.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-29-a-las-13.28.03_d570d768.jpg\" alt=\"\" width=\"228\" height=\"304\" \/><\/a> precios de esc\u00e1ndalo: \u00a1complementos a 1 euro, jers\u00e9is a 2 euros y abrigos a 3 euros! A pesar del d\u00eda de lluvia,<strong> el \u00e9xito super\u00f3 todas las expectativas:<\/strong> cu\u00e1les para entrar que daban la vuelta a la espalda a pesar de la lluvia, repusimos producto sin descanso, e hicimos muchas m\u00e1s ventas de las esperadas.<\/p>\n<p><a href=\"https:\/\/solidanca.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-29-a-las-13.27.35_178167df.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-64552\" src=\"https:\/\/solidanca.cat\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-29-a-las-13.27.35_178167df.jpg\" alt=\"\" width=\"373\" height=\"280\" \/><\/a>El balance de la jornada ha sido m\u00e1s que satisfactorio:<strong> se vendieron m\u00e1s de 3.000 productos;<\/strong> 1.028 abrigos, 1.035 jers\u00e9is, 865 complementos, 80 pantalones, 17 anoraks de esqu\u00ed y 14 pantalones de esqu\u00ed. Esto supone la<strong> gesti\u00f3n de 6.988 kg de residuo textil y un ahorro de 123.090 kg en las emisiones de CO\u2082 q<\/strong>ue evitamos en la atm\u00f3sfera con la reutilizaci\u00f3n de este textil, concretamente.<\/p>\n<p>Vuestras compras sostenibles y responsables a trav\u00e9s del mercado<strong> han evitado al planeta 132 toneladas de CO\u2082<\/strong>. Adem\u00e1s de este impacto medioambiental,<strong> las compras tambi\u00e9n repercuten positivamente en la labor social que hacemos desde Solidan\u00e7a:<\/strong> los beneficios econ\u00f3micos extra\u00eddos durante la jornada se reintroducir\u00e1n en la entidad, como refuerzo en la tarea social de inserci\u00f3n sociolaboral de colectivos en situaci\u00f3n de vulnerabilidad social mediante itinerarios de inserci\u00f3n.<\/p>\n<p>Compartimos con vosotros el Reel de recopilaci\u00f3n:\u00a0<strong><a href=\"https:\/\/www.instagram.com\/reel\/DBlThd3ohRU\/?igsh=MWJka2Q0Z296NDNhNA==\" target=\"_blank\" rel=\"noopener\">en este enlace.<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>\u00bfQuieres saber de d\u00f3nde ve la ropa? \u00a1Te explicamos el ciclo del textil!<\/strong><\/em><\/p>\n<p>El proceso de gesti\u00f3n del residuo textil con Solidan\u00e7a comienza con la recogida de ropa en los contenedores naranjas de Roba Amiga gestionados por la entidad, que es trasladado a la planta de Preparaci\u00f3n para la Reutilizaci\u00f3n de Sant Just Desvern (donde se hizo el Mercado! ) y pasa por un proceso clasificaci\u00f3n en funci\u00f3n del estado y la tipolog\u00eda de las piezas, prepar\u00e1ndolas para su reutilizaci\u00f3n y, en caso de ser necesario, el reciclaje.<\/p>\n<p>Una vez seleccionadas, aquellas peces aptas para una segunda vida, son distribuidas en la red de tiendas de Solidan\u00e7a\/ Roba Amiga, con 17 tiendas distribuidas por el territorio catal\u00e1n. En este caso, hemos decidido tambi\u00e9n poner el excedente de ropa de invierno en venta en un nuevo formato: un mercado de segunda mano con precios s\u00faper asequibles en un espacio grande y accesible para toda la poblaci\u00f3n. Debido a la gran acogida estamos trabajando para ofreceros nuevas ediciones del Mercado pr\u00f3ximamente, \u00a1est\u00e9n atentos!<\/p>\n<p>Con la compra de estos productos, contribuyes a cerrar el c\u00edrculo de la econom\u00eda circular y el ciclo de la ropa, convirtiendo el residuo en recurso y evitando generar nuevos residuos textiles.<\/p>\n<p><strong>Convertimos el residuo en recurso, hacemos econom\u00eda circular<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 26 de octubre celebramos el primer Mercado de Abrigos y Ropa de invierno de segunda mano en la Planta&#8230;<\/p>\n","protected":false},"author":2,"featured_media":7468,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[765,8],"tags":[],"class_list":["post-8755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roba-amiga-2","category-sin-categorizar"],"taxonomy_info":{"category":[{"value":765,"label":"Roba Amiga"},{"value":8,"label":"Sin categorizar"}]},"featured_image_src_large":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-10-29T133359.420-4.jpg",800,400,false],"author_info":{"display_name":"Solidan\u00e7a","author_link":"https:\/\/solidanca.cat\/es\/author\/alberg\/"},"comment_info":0,"category_info":[{"term_id":765,"name":"Roba Amiga","slug":"roba-amiga-2","term_group":0,"term_taxonomy_id":765,"taxonomy":"category","description":"","parent":0,"count":46,"filter":"raw","cat_ID":765,"category_count":46,"category_description":"","cat_name":"Roba Amiga","category_nicename":"roba-amiga-2","category_parent":0},{"term_id":8,"name":"Sin categorizar","slug":"sin-categorizar","term_group":0,"term_taxonomy_id":8,"taxonomy":"category","description":"","parent":0,"count":199,"filter":"raw","cat_ID":8,"category_count":199,"category_description":"","cat_name":"Sin categorizar","category_nicename":"sin-categorizar","category_parent":0}],"tag_info":false,"uagb_featured_image_src":{"full":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-10-29T133359.420-4.jpg",800,400,false],"thumbnail":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-10-29T133359.420-4-150x150.jpg",150,150,true],"medium":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-10-29T133359.420-4-300x150.jpg",300,150,true],"medium_large":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-10-29T133359.420-4-768x384.jpg",768,384,true],"large":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-10-29T133359.420-4.jpg",800,400,false],"1536x1536":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-10-29T133359.420-4.jpg",800,400,false],"2048x2048":["https:\/\/solidanca.cat\/wp-content\/uploads\/2025\/04\/FOTO-NOTICIES-WEB-2024-10-29T133359.420-4.jpg",800,400,false]},"uagb_author_info":{"display_name":"Solidan\u00e7a","author_link":"https:\/\/solidanca.cat\/es\/author\/alberg\/"},"uagb_comment_info":0,"uagb_excerpt":"El s\u00e1bado 26 de octubre celebramos el primer Mercado de Abrigos y Ropa de invierno de segunda mano en la Planta...","_links":{"self":[{"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/posts\/8755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/comments?post=8755"}],"version-history":[{"count":0,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/posts\/8755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/media\/7468"}],"wp:attachment":[{"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/media?parent=8755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/categories?post=8755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solidanca.cat\/es\/wp-json\/wp\/v2\/tags?post=8755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}